{"id":166713,"date":"2026-05-13T12:08:29","date_gmt":"2026-05-13T12:08:29","guid":{"rendered":"https:\/\/friss-hirek.hu\/index.php\/vitezy-david-uj-terve-mindent-atirhat-a-balatonnal-sokan-nem-erre-szamitottak-a-korvasutnal\/friss-hirek\/"},"modified":"2026-05-13T12:08:29","modified_gmt":"2026-05-13T12:08:29","slug":"vitezy-david-uj-terve-mindent-atirhat-a-balatonnal-sokan-nem-erre-szamitottak-a-korvasutnal","status":"publish","type":"post","link":"https:\/\/friss-hirek.hu\/index.php\/vitezy-david-uj-terve-mindent-atirhat-a-balatonnal-sokan-nem-erre-szamitottak-a-korvasutnal\/videk\/","title":{"rendered":"Vit\u00e9zy D\u00e1vid \u00faj terve mindent \u00e1t\u00edrhat a Balatonn\u00e1l: sokan nem erre sz\u00e1m\u00edtottak a k\u00f6rvas\u00fatn\u00e1l"},"content":{"rendered":"<p>Nem biztos, hogy a Balaton k\u00f6r\u00fcl v\u00e9gig fels\u0151vezet\u00e9ket h\u00faznak ki: Vit\u00e9zy D\u00e1vid szerint ink\u00e1bb akkumul\u00e1toros vonatokkal lehetne megoldani a r\u00e9g\u00f3ta tervezett fejleszt\u00e9st.<\/p><div id=\"friss-4087242323\" class=\"friss-etarget-cikk-vege friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-1864569993\" class=\"friss-etarget friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-2447066561\" class=\"friss-after-content friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-3255370607\" class=\"friss-after-content_2 friss-entity-placement\" style=\"clear: both;\"><div class=\"wprss_ajax\" data-id=\"rssd26b21ae62\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/friss-hirek.hu\/wp-content\/plugins\/wp-rss-retriever\/inc\/imgs\/ajax-loader.gif\" alt=\"Loading RSS Feed\" width=\"16\" height=\"16\"><\/div><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"friss-2804449586\" class=\"friss-after-content_3 friss-entity-placement\">https:\/\/www.youtube.com\/watch?v=Pdnw4KiUWp0<\/div>","protected":false},"excerpt":{"rendered":"<p>Nem biztos, hogy a Balaton k\u00f6r\u00fcl v\u00e9gig fels\u0151vezet\u00e9ket h\u00faznak ki: Vit\u00e9zy D\u00e1vid szerint ink\u00e1bb akkumul\u00e1toros vonatokkal lehetne megoldani a r\u00e9g\u00f3ta tervezett fejleszt\u00e9st.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-166713","post","type-post","status-publish","format-standard","hentry","category-videk"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/166713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/comments?post=166713"}],"version-history":[{"count":0,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/166713\/revisions"}],"wp:attachment":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/media?parent=166713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/categories?post=166713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/tags?post=166713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}