{"id":169040,"date":"2026-07-14T06:29:32","date_gmt":"2026-07-14T06:29:32","guid":{"rendered":"https:\/\/friss-hirek.hu\/index.php\/kozuti-kaosz-somogy-varmegyeben-kitalalod-hogy-hany-ittas-vezetot-fogtak-hetvegen-a-rendorok\/friss-hirek\/"},"modified":"2026-07-14T06:29:32","modified_gmt":"2026-07-14T06:29:32","slug":"kozuti-kaosz-somogy-varmegyeben-kitalalod-hogy-hany-ittas-vezetot-fogtak-hetvegen-a-rendorok","status":"publish","type":"post","link":"https:\/\/friss-hirek.hu\/index.php\/kozuti-kaosz-somogy-varmegyeben-kitalalod-hogy-hany-ittas-vezetot-fogtak-hetvegen-a-rendorok\/auto\/","title":{"rendered":"K\u00f6z\u00fati k\u00e1osz Somogy v\u00e1rmegy\u00e9ben: Kital\u00e1lod, hogy h\u00e1ny ittas vezet\u0151t fogtak h\u00e9tv\u00e9g\u00e9n a rend\u0151r\u00f6k?"},"content":{"rendered":"<p>Aut\u00f3sok, motorosok \u00e9s rolleresek is fennakadtak a somogyi rend\u0151rs\u00e9g h\u00e9tv\u00e9gi ellen\u0151rz\u00e9sein. Az egyik sof\u0151r eltilt\u00e1s hat\u00e1lya alatt vezetett.<\/p><div id=\"friss-2024113985\" class=\"friss-etarget-cikk-vege friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-4258049085\" class=\"friss-etarget friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-416280694\" class=\"friss-after-content friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-3091823654\" class=\"friss-after-content_2 friss-entity-placement\" style=\"clear: both;\"><div class=\"wprss_ajax\" data-id=\"rss6d44c6a535\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/friss-hirek.hu\/wp-content\/plugins\/wp-rss-retriever\/inc\/imgs\/ajax-loader.gif\" alt=\"Loading RSS Feed\" width=\"16\" height=\"16\"><\/div><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"friss-536005630\" class=\"friss-after-content_3 friss-entity-placement\">https:\/\/www.youtube.com\/watch?v=Pdnw4KiUWp0<\/div>","protected":false},"excerpt":{"rendered":"<p>Aut\u00f3sok, motorosok \u00e9s rolleresek is fennakadtak a somogyi rend\u0151rs\u00e9g h\u00e9tv\u00e9gi ellen\u0151rz\u00e9sein. Az egyik sof\u0151r eltilt\u00e1s hat\u00e1lya alatt vezetett.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-169040","post","type-post","status-publish","format-standard","hentry","category-auto"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/169040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/comments?post=169040"}],"version-history":[{"count":0,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/169040\/revisions"}],"wp:attachment":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/media?parent=169040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/categories?post=169040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/tags?post=169040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}