{"id":169252,"date":"2026-07-18T06:39:43","date_gmt":"2026-07-18T06:39:43","guid":{"rendered":"https:\/\/friss-hirek.hu\/index.php\/most-kozolte-a-gyori-utkezelo-a-lakosokkal-szallittatjak-el-az-azbeszttel-szennyezett-kozuzelekot\/friss-hirek\/"},"modified":"2026-07-18T06:39:43","modified_gmt":"2026-07-18T06:39:43","slug":"most-kozolte-a-gyori-utkezelo-a-lakosokkal-szallittatjak-el-az-azbeszttel-szennyezett-kozuzelekot","status":"publish","type":"post","link":"https:\/\/friss-hirek.hu\/index.php\/most-kozolte-a-gyori-utkezelo-a-lakosokkal-szallittatjak-el-az-azbeszttel-szennyezett-kozuzelekot\/videk\/","title":{"rendered":"Most k\u00f6z\u00f6lte a gy\u0151ri \u00fatkezel\u0151: a lakosokkal sz\u00e1ll\u00edttatj\u00e1k el az azbeszttel szennyezett k\u0151z\u00fazel\u00e9kot"},"content":{"rendered":"<p>Az \u00fatkezel\u0151 t\u00e9ves t\u00e1j\u00e9koztat\u00e1sa miatt a gy\u0151ri lakoss\u00e1g csak j\u00falius elej\u00e9n \u00e9rtes\u00fclhetett arr\u00f3l, hogy azbeszttartalm\u00fa k\u0151z\u00fazal\u00e9k ker\u00fclt a v\u00e1ros egyes lak\u00f3\u00f6vezeteibe.<\/p><div id=\"friss-3897222193\" class=\"friss-etarget-cikk-vege friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-613006756\" class=\"friss-etarget friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-3757333303\" class=\"friss-after-content friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-2079499511\" class=\"friss-after-content_2 friss-entity-placement\" style=\"clear: both;\"><div class=\"wprss_ajax\" data-id=\"rss3ce2bde610\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/friss-hirek.hu\/wp-content\/plugins\/wp-rss-retriever\/inc\/imgs\/ajax-loader.gif\" alt=\"Loading RSS Feed\" width=\"16\" height=\"16\"><\/div><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"friss-1068339476\" class=\"friss-after-content_3 friss-entity-placement\">https:\/\/www.youtube.com\/watch?v=Pdnw4KiUWp0<\/div>","protected":false},"excerpt":{"rendered":"<p>Az \u00fatkezel\u0151 t\u00e9ves t\u00e1j\u00e9koztat\u00e1sa miatt a gy\u0151ri lakoss\u00e1g csak j\u00falius elej\u00e9n \u00e9rtes\u00fclhetett arr\u00f3l, hogy azbeszttartalm\u00fa k\u0151z\u00fazal\u00e9k ker\u00fclt a v\u00e1ros egyes lak\u00f3\u00f6vezeteibe.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-169252","post","type-post","status-publish","format-standard","hentry","category-videk"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/169252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/comments?post=169252"}],"version-history":[{"count":0,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/169252\/revisions"}],"wp:attachment":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/media?parent=169252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/categories?post=169252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/tags?post=169252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}