{"id":169352,"date":"2026-07-21T06:26:28","date_gmt":"2026-07-21T06:26:28","guid":{"rendered":"https:\/\/friss-hirek.hu\/index.php\/95-millio-forint-kozpenz-ket-ejszakaert-nyilvanosak-a-volt-honvedelmi-miniszter-luxushoteles-szamlai\/friss-hirek\/"},"modified":"2026-07-21T06:26:28","modified_gmt":"2026-07-21T06:26:28","slug":"95-millio-forint-kozpenz-ket-ejszakaert-nyilvanosak-a-volt-honvedelmi-miniszter-luxushoteles-szamlai","status":"publish","type":"post","link":"https:\/\/friss-hirek.hu\/index.php\/95-millio-forint-kozpenz-ket-ejszakaert-nyilvanosak-a-volt-honvedelmi-miniszter-luxushoteles-szamlai\/uzlet\/","title":{"rendered":"9,5 milli\u00f3 forint k\u00f6zp\u00e9nz k\u00e9t \u00e9jszak\u00e1\u00e9rt: nyilv\u00e1nosak a volt honv\u00e9delmi miniszter luxushoteles sz\u00e1ml\u00e1i"},"content":{"rendered":"<p><strong>A volt honv\u00e9delmi miniszter egy tusv\u00e1nyosi utaz\u00e1s kiv\u00e9tel\u00e9vel mindig felvette 15 ezer forintos kik\u00fcldet\u00e9si napid\u00edj\u00e1t.<\/strong><\/p><div id=\"friss-4080820779\" class=\"friss-etarget friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div>\n<p><strong>Mi t\u00f6rt\u00e9nt?<\/strong> K\u00f6z\u00e9rdek\u0171 adatig\u00e9nyl\u00e9ssel fordult a <a href=\"https:\/\/24.hu\/belfold\/2026\/07\/21\/szalay-bobrovniczky-kristof-kulfoldi-utak-szalloda-honvedelmi-miniszter\/\">24.hu<\/a> a Honv\u00e9delmi Miniszt\u00e9riumhoz Szalay-Bobrovniczky Krist\u00f3f utaz\u00e1sai kapcs\u00e1n. A sz\u00e1mokb\u00f3l kider\u00fclt, hogy n\u00e9gy \u00e9ves miniszters\u00e9ge alatt a politikus szinte kiz\u00e1r\u00f3lag honv\u00e9ds\u00e9gi g\u00e9ppel rep\u00fclt, \u00e9s sz\u00e1mos \u00f6tcsillagos luxushotelben vend\u00e9geskedett. Szalay-Bobrovniczky els\u0151 NATO-cs\u00facs\u00e1n, Madridban sz\u00e1llt meg a legnagyobb k\u00e9nyelemben: k\u00e9t \u00e9jszak\u00e1ra 9 576 501 forint\u00e9rt foglaltak szob\u00e1t \u00f6ttag\u00fa deleg\u00e1ci\u00f3j\u00e1nak a Mandarin Oriental Ritz luxushotelben, ebb\u0151l a miniszter k\u00e9nyelm\u00e9re 1 596 084 forintot k\u00f6lt\u00f6ttek. Legdr\u00e1g\u00e1bb sz\u00e1llodaszob\u00e1ja azonban nem ez, hanem egy t\u00f6r\u00f6korsz\u00e1gi:<\/p>\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p> 2025 december\u00e9ben Isztambulban sz\u00e1llt meg egyf\u0151s deleg\u00e1ci\u00f3j\u00e1val a Four Seasons hotelben. Ez egy \u00e9jszak\u00e1ra 4,3 milli\u00f3 forintba ker\u00fclt, egyik\u0151j\u00fck  \u00a0a \u201eBoszporusz-palota-lakoszt\u00e1lyban\u201d pihenhetett.<\/p>\n<\/blockquote>\n<div class=\"related-post-links\">\n<p>\t\t<span class=\"related-post-links__title minititle\">T\u00f6bb ebb\u0151l<\/span><\/p>\n<div class=\"related-post-links__link-wrapper\">\n\t\t\t\t<a href=\"https:\/\/forbes.hu\/uzlet\/dunai-vasmu-leanyvallalat-csoportos-letszamleepites\/\" class=\"related-post-links__link\">150 embert r\u00fagtak ki a Dunai Vasm\u0171 energiaell\u00e1t\u00f3j\u00e1t\u00f3l, komoly gondok j\u00f6hetnek t\u00e9len<\/a>\n\t\t\t<\/div>\n<div class=\"related-post-links__link-wrapper\">\n\t\t\t\t<a href=\"https:\/\/forbes.hu\/penz\/adaz-verseny-folyik-a-mobilunkban-ezekkel-az-ujdonsagokkal-rukkoltak-elo-a-bankok\/\" class=\"related-post-links__link\">A Revolut nagy dob\u00e1sa ut\u00e1n m\u00e9g \u00e1d\u00e1zabb a verseny a mobilunkban \u2013 ezekkel az \u00fajdons\u00e1gokkal rukkoltak el\u0151 a bankok<\/a>\n\t\t\t<\/div>\n<\/div>\n<p><strong>Mit kell m\u00e9g tudni?<\/strong> Szalay-Bobrovniczky a n\u00e9gy \u00e9v alatt 35 k\u00fcl\u00f6nb\u00f6z\u0151 orsz\u00e1g 51 k\u00fcl\u00f6nb\u00f6z\u0151 v\u00e1ros\u00e1ba l\u00e1togatott el. A legt\u00f6bbsz\u00f6r a NATO v\u00e9delmi miniszteri \u00fcl\u00e9sein j\u00e1rt, leggyakrabban pedig Br\u00fcsszelbe utazott. A honv\u00e9delmi miniszter szinte 90 regisztr\u00e1lt \u00fatj\u00e1b\u00f3l 78 alkalommal rep\u00fclt honv\u00e9ds\u00e9gi g\u00e9ppel, \u00e9s mind\u00f6ssze egyszer fordult el\u0151, hogy nem vette fel 15 ezer forintos kik\u00fcldet\u00e9si napid\u00edj\u00e1t \u2013 amikor Tusv\u00e1nyosra l\u00e1togatott.<\/p>\n<p><!-- No email blocks found --><\/p>\n<p>The post <a href=\"https:\/\/forbes.hu\/penz\/szalay-bobrovniczky-hotel-lakosztaly-spanyolorszag-kozpenz\/\">9,5 milli\u00f3 forint k\u00f6zp\u00e9nz k\u00e9t \u00e9jszak\u00e1\u00e9rt: nyilv\u00e1nosak a volt honv\u00e9delmi miniszter luxushoteles sz\u00e1ml\u00e1i<\/a> appeared first on <a href=\"https:\/\/forbes.hu\/\">Forbes.hu<\/a>.<\/p><div id=\"friss-4028303824\" class=\"friss-etarget-cikk-vege friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-298295071\" class=\"friss-after-content friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-1475954105\" class=\"friss-after-content_2 friss-entity-placement\" style=\"clear: both;\"><div class=\"wprss_ajax\" data-id=\"rss87576db79a\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/friss-hirek.hu\/wp-content\/plugins\/wp-rss-retriever\/inc\/imgs\/ajax-loader.gif\" alt=\"Loading RSS Feed\" width=\"16\" height=\"16\"><\/div><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"friss-1631045514\" class=\"friss-after-content_3 friss-entity-placement\">https:\/\/www.youtube.com\/watch?v=Pdnw4KiUWp0<\/div>","protected":false},"excerpt":{"rendered":"<p>A volt honv\u00e9delmi miniszter egy tusv\u00e1nyosi utaz\u00e1s kiv\u00e9tel\u00e9vel mindig felvette 15 ezer forintos kik\u00fcldet\u00e9si napid\u00edj\u00e1t. Mi t\u00f6rt\u00e9nt? K\u00f6z\u00e9rdek\u0171 adatig\u00e9nyl\u00e9ssel fordult a 24.hu a Honv\u00e9delmi Miniszt\u00e9riumhoz Szalay-Bobrovniczky Krist\u00f3f utaz\u00e1sai kapcs\u00e1n. A sz\u00e1mokb\u00f3l kider\u00fclt, hogy n\u00e9gy \u00e9ves miniszters\u00e9ge alatt a politikus szinte kiz\u00e1r\u00f3lag honv\u00e9ds\u00e9gi g\u00e9ppel rep\u00fclt, \u00e9s sz\u00e1mos \u00f6tcsillagos luxushotelben vend\u00e9geskedett. Szalay-Bobrovniczky els\u0151 NATO-cs\u00facs\u00e1n, Madridban sz\u00e1llt meg [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-169352","post","type-post","status-publish","format-standard","hentry","category-uzlet"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/169352","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/comments?post=169352"}],"version-history":[{"count":0,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/169352\/revisions"}],"wp:attachment":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/media?parent=169352"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/categories?post=169352"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/tags?post=169352"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}