{"id":170319,"date":"2026-08-13T07:08:55","date_gmt":"2026-08-13T07:08:55","guid":{"rendered":"https:\/\/friss-hirek.hu\/index.php\/video-versenyezni-akartak-a-jaszberenyi-ejszakaban-nem-jutottak-messzire\/friss-hirek\/"},"modified":"2026-08-13T07:08:55","modified_gmt":"2026-08-13T07:08:55","slug":"video-versenyezni-akartak-a-jaszberenyi-ejszakaban-nem-jutottak-messzire","status":"publish","type":"post","link":"https:\/\/friss-hirek.hu\/index.php\/video-versenyezni-akartak-a-jaszberenyi-ejszakaban-nem-jutottak-messzire\/auto\/","title":{"rendered":"Vide\u00f3: versenyezni akartak a j\u00e1szber\u00e9nyi \u00e9jszak\u00e1ban, nem jutottak messzire!"},"content":{"rendered":"<p>Az elk\u00f6vet\u0151k j\u00f3 \u00f6tletnek gondolt\u00e1k, hogy J\u00e1szber\u00e9ny belv\u00e1ros\u00e1ban sz\u00e1guldozzanak az \u00e9j leple alatt, azonban a verseny nem tartott sok\u00e1ig. \u00cdme a vide\u00f3!<\/p><div id=\"friss-2415019434\" class=\"friss-etarget-cikk-vege friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-225250094\" class=\"friss-etarget friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-543655798\" class=\"friss-after-content friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-666112112\" class=\"friss-after-content_2 friss-entity-placement\" style=\"clear: both;\"><div class=\"wprss_ajax\" data-id=\"rssbc5d5b514e\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/friss-hirek.hu\/wp-content\/plugins\/wp-rss-retriever\/inc\/imgs\/ajax-loader.gif\" alt=\"Loading RSS Feed\" width=\"16\" height=\"16\"><\/div><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"friss-2075659699\" class=\"friss-after-content_3 friss-entity-placement\">https:\/\/www.youtube.com\/watch?v=Pdnw4KiUWp0<\/div>","protected":false},"excerpt":{"rendered":"<p>Az elk\u00f6vet\u0151k j\u00f3 \u00f6tletnek gondolt\u00e1k, hogy J\u00e1szber\u00e9ny belv\u00e1ros\u00e1ban sz\u00e1guldozzanak az \u00e9j leple alatt, azonban a verseny nem tartott sok\u00e1ig. \u00cdme a vide\u00f3!<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8],"tags":[],"class_list":["post-170319","post","type-post","status-publish","format-standard","hentry","category-auto"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/170319","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/comments?post=170319"}],"version-history":[{"count":0,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/170319\/revisions"}],"wp:attachment":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/media?parent=170319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/categories?post=170319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/tags?post=170319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}