{"id":171070,"date":"2026-09-02T05:39:05","date_gmt":"2026-09-02T05:39:05","guid":{"rendered":"https:\/\/friss-hirek.hu\/index.php\/egyre-tobben-alkalmazzak-a-kulonleges-modszert-ezert-kerul-zsak-a-fiatal-fakra\/friss-hirek\/"},"modified":"2026-09-02T05:39:05","modified_gmt":"2026-09-02T05:39:05","slug":"egyre-tobben-alkalmazzak-a-kulonleges-modszert-ezert-kerul-zsak-a-fiatal-fakra","status":"publish","type":"post","link":"https:\/\/friss-hirek.hu\/index.php\/egyre-tobben-alkalmazzak-a-kulonleges-modszert-ezert-kerul-zsak-a-fiatal-fakra\/videk\/","title":{"rendered":"Egyre t\u00f6bben alkalmazz\u00e1k a k\u00fcl\u00f6nleges m\u00f3dszert \u2013 ez\u00e9rt ker\u00fcl zs\u00e1k a fiatal f\u00e1kra"},"content":{"rendered":"<p>Egyre t\u00f6bb \u00f6nt\u00f6z\u0151zs\u00e1kot l\u00e1tni Gy\u0151r fiatal f\u00e1i k\u00f6r\u00fcl: a v\u00e1ros t\u00f6bb pontj\u00e1n, k\u00fcl\u00f6n\u00f6sen az \u00fajonnan \u00fcltetett facsemet\u00e9kn\u00e9l alkalmazz\u00e1k a m\u00f3dszert, amely a nagy ny\u00e1ri h\u0151s\u00e9gben komoly seg\u00edts\u00e9get jelent a n\u00f6v\u00e9nyek v\u00edzell\u00e1t\u00e1s\u00e1ban, \u00edrja a <a href=\"https:\/\/www.kisalfold.hu\/helyi-kozelet\/2026\/09\/ontozozsak-gyori-facsemetek-kertesz\" target=\"_blank\" rel=\"noopener\">Kisalf\u00f6ld.<\/a><\/p><div id=\"friss-1672790721\" class=\"friss-etarget friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div>\n<p><strong>Nagykutasi Viktor,<\/strong> a Kert\u00e9szek \u00e9s Kertbar\u00e1tok Gy\u0151r V\u00e1rosi Egyes\u00fclet\u00e9nek eln\u00f6ke k\u00f6z\u00f6lte, hogy a technol\u00f3gia nem \u00faj kelet\u0171, Magyarorsz\u00e1gon mintegy \u00f6t-hat \u00e9ve jelent meg, els\u0151sorban a nagyv\u00e1rosokban \u00e9s kert\u00e9szeti c\u00e9gek alkalmaz\u00e1s\u00e1ban.<\/p>\n<p>Gy\u0151rben egy-egy eszk\u00f6zbe k\u00f6r\u00fclbel\u00fcl 50\u201370 liter v\u00edz f\u00e9r, ami egy frissen \u00fcltetett fa ak\u00e1r egyheti v\u00edzig\u00e9ny\u00e9t is fedezheti.<\/p>\n<blockquote class=\"_ce_measure_widget\" data-ce-measure-widget=\"Id\u00e9zet\">\n<p>A fa\u00fcltet\u00e9skor a t\u00f6rzs k\u00f6r\u00fcl kialak\u00edtunk egy \u00fagynevezett t\u00e1ny\u00e9rt, ebbe azonban legfeljebb 20 liter v\u00edz f\u00e9r. Egy \u00f6nt\u00f6z\u0151zs\u00e1kkal ennek ak\u00e1r a h\u00e1romszoros\u00e1t is ki tudjuk juttatni. A legfontosabb el\u0151nye azonban az, hogy a v\u00edz nem egyszerre ker\u00fcl a talajra, hanem 3\u20138 \u00f3ra alatt, lassan sziv\u00e1rog ki<\/p>\n<\/blockquote>\n<p>\u2013 magyar\u00e1zta a kert\u00e9sz szak\u00edr\u00f3.<\/p>\n<p>A csepegtet\u0151 m\u00f3dszernek k\u00f6sz\u00f6nhet\u0151en a v\u00edz nem sz\u00e9tter\u00fcl a felsz\u00ednen, hanem fokozatosan lefel\u00e9 jut a talajba, \u00edgy m\u00e9lyebben \u00e9ri el a gy\u00f6k\u00e9rzetet. Ez el\u0151seg\u00edti, hogy a fa m\u00e9lyrehat\u00f3 gy\u00f6k\u00e9rzetet fejlesszen, \u00e9s tov\u00e1bb meg\u0151rizze a nedvess\u00e9get. A zs\u00e1k r\u00e1ad\u00e1sul \u00e1rny\u00e9kolja a talajt \u00e9s m\u00e9rs\u00e9kli a p\u00e1rolg\u00e1st, ugyanakkor a szakember szerint a t\u00falzott nedvess\u00e9g miatt a gomb\u00e1sod\u00e1s vesz\u00e9ly\u00e9vel is sz\u00e1molni kell.<\/p>\n<p>Az \u00f6nt\u00f6z\u0151zs\u00e1kok k\u00fcl\u00f6nb\u00f6z\u0151 m\u00e9ret\u0171 f\u00e1khoz is haszn\u00e1lhat\u00f3k, vastagabb t\u00f6rzs eset\u00e9n ak\u00e1r t\u00f6bb zs\u00e1k is \u00f6sszekapcsolhat\u00f3. Felt\u00f6lt\u00e9s\u00fck egyszer\u0171: otthoni k\u00f6r\u00fclm\u00e9nyek k\u00f6z\u00f6tt ak\u00e1r kann\u00e1val is megoldhat\u00f3, Gy\u0151rben pedig a Gy\u0151r-Szol Zrt. munkat\u00e1rsai locsol\u00f3cs\u00f6v\u00f6n kereszt\u00fcl gondoskodnak a p\u00f3tl\u00e1sukr\u00f3l, olvashat\u00f3 a cikkben.<\/p>\n<p>Az egy\u00e9bk\u00e9nt d\u00f6bbenetes, mennyi iv\u00f3vizet locsolunk el a kertben: <a href=\"https:\/\/sokszinuvidek.24.hu\/kertunk-portank\/2026\/06\/30\/dobbenetes-mennyi-ivovizet-locsolunk-el-a-kertben-itt-vannak-a-szamok\/\" target=\"_blank\" rel=\"noopener\">itt vannak a sz\u00e1mok.<\/a><\/p>\n<div class=\"o-post__articRecommend m-articRecommend -hasImg cf article-recommendation-container cf _ce_measure_widget\" data-ce-measure-widget=\"Cikkaj\u00e1nl\u00f3 widget\">\n<div class=\"m-articRecommend__widgetTitle\">Kapcsol\u00f3d\u00f3<\/div>\n<div class=\"m-articRecommend__imgWrap image-container\"><a href=\"https:\/\/sokszinuvidek.24.hu\/kertunk-portank\/2026\/09\/01\/evelo-szeptember-szaporitas\/\" target=\"_self\"><img loading=\"lazy\" decoding=\"async\" width=\"480\" height=\"270\" src=\"https:\/\/s.24.hu\/app\/uploads\/sites\/11\/2026\/08\/jhenning-summer-5393330_1280-e1787932272925-480x270.jpg\" class=\"img-responsive wp-post-image\" alt=\"\" \/><\/a><\/div>\n<div class=\"m-articRecommend__cntWrap content-container \">\n\t\t\t<a href=\"https:\/\/sokszinuvidek.24.hu\/kertunk-portank\/2026\/09\/01\/evelo-szeptember-szaporitas\/\" target=\"_self\" class=\"m-articRecommend__title ar-title\">10 \u00e9vel\u0151, amit szeptemberben \u00e9rdemes szapor\u00edtani, hogy j\u00f6v\u0151re m\u00e9g szebb legyen a kert<\/a>\n<div class=\"m-articRecommend__lead ar-lead\">Szeptember ide\u00e1lis id\u0151szak sz\u00e1mos \u00e9vel\u0151 n\u00f6v\u00e9ny szapor\u00edt\u00e1s\u00e1ra.<\/div>\n<\/div>\n<\/div>\n<p>The post <a href=\"https:\/\/sokszinuvidek.24.hu\/kertunk-portank\/2026\/09\/02\/ontozozsak-elonyei\/\" target=\"_blank\">Egyre t\u00f6bben alkalmazz\u00e1k a k\u00fcl\u00f6nleges m\u00f3dszert \u2013 ez\u00e9rt ker\u00fcl zs\u00e1k a fiatal f\u00e1kra<\/a> first appeared on <a href=\"https:\/\/sokszinuvidek.24.hu\/\" target=\"_blank\">Soksz\u00edn\u0171 vid\u00e9k<\/a>.<\/p><div id=\"friss-2546785399\" class=\"friss-etarget-cikk-vege friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-2955034680\" class=\"friss-after-content friss-entity-placement\"><script type=\"text\/javascript\" id=\"etargetScript7a9b589f63cb072bef80df221f46a22b\">function etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b(){var e=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",t=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",o=document.getElementById(e);if(o){for(var n=o.offsetTop,d=o.offsetLeft,r=o.offsetWidth,a=o.offsetHeight;o.offsetParent;)o=o.offsetParent,n+=o.offsetTop,d+=o.offsetLeft;var i=(n<=window.pageYOffset+window.innerHeight&&d<window.pageXOffset+window.innerWidth&&n+a>window.pageYOffset&&d+r>window.pageXOffset);if(i&&etargetAllowOtherCheck){allowed=!1;var c=document.createElement(\"script\");return c.src=\"\/\/hu.search.etargetnet.com\/generic\/uni.php?g=ref:58661,area:700x210\",void(document.getElementById(t)&&document.getElementById(e)&&(document.getElementById(t).parentNode.appendChild(c),document.getElementById(t).parentNode.removeChild(document.getElementById(t)),document.getElementById(e).parentNode.removeChild(document.getElementById(e)),document.removeEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.removeEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b)))}}}var etargetDivID=\"etargetPostload7a9b589f63cb072bef80df221f46a22b\",etargetScriptID=\"etargetScript7a9b589f63cb072bef80df221f46a22b\",etargetPostloadPoint=document.createElement(\"div\");etargetPostloadPoint.id=etargetDivID;var etargetCurScript=document.getElementById(etargetScriptID);etargetCurScript.parentNode.appendChild(etargetPostloadPoint),document.addEventListener(\"scroll\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"resize\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b),document.addEventListener(\"DOMContentLoaded\",etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b);var etargetAllowOtherCheck=!0;if(typeof(\"forceRunPostload\")==\"string\"){etargetPostloadFunction7a9b589f63cb072bef80df221f46a22b()}<\/script><\/div><div id=\"friss-2254710666\" class=\"friss-after-content_2 friss-entity-placement\" style=\"clear: both;\"><div class=\"wprss_ajax\" data-id=\"rss92a8c2935f\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/friss-hirek.hu\/wp-content\/plugins\/wp-rss-retriever\/inc\/imgs\/ajax-loader.gif\" alt=\"Loading RSS Feed\" width=\"16\" height=\"16\"><\/div><\/div><br style=\"clear: both; display: block; float: none;\"\/><div id=\"friss-1297913865\" class=\"friss-after-content_3 friss-entity-placement\">https:\/\/www.youtube.com\/watch?v=Pdnw4KiUWp0<\/div>","protected":false},"excerpt":{"rendered":"<p>Egyre t\u00f6bb \u00f6nt\u00f6z\u0151zs\u00e1kot l\u00e1tni Gy\u0151r fiatal f\u00e1i k\u00f6r\u00fcl: a v\u00e1ros t\u00f6bb pontj\u00e1n, k\u00fcl\u00f6n\u00f6sen az \u00fajonnan \u00fcltetett facsemet\u00e9kn\u00e9l alkalmazz\u00e1k a m\u00f3dszert, amely a nagy ny\u00e1ri h\u0151s\u00e9gben komoly seg\u00edts\u00e9get jelent a n\u00f6v\u00e9nyek v\u00edzell\u00e1t\u00e1s\u00e1ban, \u00edrja a Kisalf\u00f6ld. Nagykutasi Viktor, a Kert\u00e9szek \u00e9s Kertbar\u00e1tok Gy\u0151r V\u00e1rosi Egyes\u00fclet\u00e9nek eln\u00f6ke k\u00f6z\u00f6lte, hogy a technol\u00f3gia nem \u00faj kelet\u0171, Magyarorsz\u00e1gon mintegy \u00f6t-hat \u00e9ve [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-171070","post","type-post","status-publish","format-standard","hentry","category-videk"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/171070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/comments?post=171070"}],"version-history":[{"count":0,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/posts\/171070\/revisions"}],"wp:attachment":[{"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/media?parent=171070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/categories?post=171070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/friss-hirek.hu\/index.php\/wp-json\/wp\/v2\/tags?post=171070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}